{"id":3279,"date":"2026-07-03T15:43:37","date_gmt":"2026-07-03T13:43:37","guid":{"rendered":"https:\/\/emmyskerzen.com\/?post_type=product&#038;p=3279"},"modified":"2026-09-01T21:18:03","modified_gmt":"2026-09-01T19:18:03","slug":"lavendel-honig-duftkerze","status":"publish","type":"product","link":"https:\/\/emmyskerzen.com\/en\/shop\/lavendel-honig-duftkerze\/","title":{"rendered":"Lavendel-Honig Duftkerze"},"content":{"rendered":"<h3 dir=\"ltr\">Lavendel-Honig Duftkerze aus 100 % Sojawachs<\/h3>\n<div dir=\"ltr\">\n<p>Bringe die beruhigende Atmosph\u00e4re eines bl\u00fchenden Lavendelfeldes in dein Zuhause. Diese liebevoll handgefertigte Lavendel-Honig Duftkerze kombiniert den entspannenden Duft von Lavendel mit der warmen, sanften S\u00fc\u00dfe von Honig. Das harmonische Duftspiel sorgt f\u00fcr Wohlf\u00fchlmomente und eine gem\u00fctliche Atmosph\u00e4re.<\/p>\n<p>Jede Kerze wird in \u00d6sterreich aus 100 % nat\u00fcrlichem Sojawachs von Hand gegossen und mit viel Liebe zum Detail verziert. Die aufwendigen Wachsdekorationen \u2013 darunter eine Honigwabe und eine kleine Biene \u2013 machen jede Kerze zu einem einzigartigen Unikat.<\/p>\n<p>Die Lavendel-Honig Duftkerze eignet sich hervorragend als stilvolle Dekoration f\u00fcr Wohn-, Schlaf- oder Badezimmer und ist gleichzeitig eine wundersch\u00f6ne Geschenkidee f\u00fcr Geburtstage, Muttertag, Einzug oder einfach als kleine Aufmerksamkeit f\u00fcr einen lieben Menschen.<\/p>\n<p>Produktdetails<\/p>\n<ul>\n<li>Handgefertigt in \u00d6sterreich<\/li>\n<li>100 % hochwertiges Sojawachs<\/li>\n<li>300ml<\/li>\n<li>Duft: Lavendel &amp; Honig<\/li>\n<li>Liebevoll verzierte Wachsdekorationen<\/li>\n<li>Baumwolldochte f\u00fcr ein ruhiges Abbrennen<\/li>\n<li>Jede Kerze ist ein handgefertigtes Unikat<\/li>\n<li>Perfekt als Geschenk oder stilvolle Wohnraumdekoration<\/li>\n<\/ul>\n<p>Hinweis: Da jede Kerze von Hand gefertigt wird, k\u00f6nnen Form und Dekoration leicht variieren. Genau das macht jede Kerze zu einem einzigartigen Einzelst\u00fcck.<\/p>\n<\/div>\n<div><\/div>\n<div>Hier findest du noch mehr wunderbare Duftkerzen von Emmys Kerzen: <a href=\"https:\/\/emmyskerzen.com\/en\/handgemachte-duftkerzen\/\">Scented Candles<\/a><\/div>\n<div><a href=\"https:\/\/emmyskerzen.com\/en\/duftkerzen-sommer-2026-trend\/\">Duftkerzen im Sommer?\u00a0<\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div dir=\"ltr\">\n<p>*Gesamtpreis, umsatzsteuerbefreit aufgrund des Kleinunternehmerstatus, zuz\u00fcglich Versandkosten.<\/p>\n<p>Produktidentifikation: Lavendel-Honig Duftkerze<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><span data-olk-copy-source=\"MessageBody\">Handgefertigte Lavendel-Honig Duftkerze aus 100 % Sojawachs mit liebevollen Wachsdekorationen \u2013 f\u00fcr entspannte Wohlf\u00fchlmomente.<\/span><\/p>","protected":false},"featured_media":3280,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[514,858,857,859],"product_tag":[582,45,867,865,39,874,873,189,434,42,866,426,743,869,868,864,870,872,482,200,225,871],"class_list":["post-3279","product","type-product","status-publish","has-post-thumbnail","product_cat-duftkerze","product_cat-fruehlingskerzen","product_cat-geschenkkerzen-geschenksets","product_cat-sommerkerzen","product_tag-bienenkerze","product_tag-duftkerze","product_tag-duftkerze-honig","product_tag-duftkerze-lavendel","product_tag-emmys-kerzen","product_tag-frischer-duft-kerze","product_tag-fruehlingskerze-bienen","product_tag-geschenkidee-kerze","product_tag-handgemacht-in-oesterreich","product_tag-handgemachte-kerze","product_tag-honig-dufterze","product_tag-kerze-aus-oesterreich","product_tag-kerzen-online-kaufen","product_tag-lavendel-honig","product_tag-lavendel-honig-duftkerze","product_tag-lavendelkerze","product_tag-lavender-honey","product_tag-naturduft-kerze","product_tag-onlineshop-oesterreich","product_tag-sojawachskerze","product_tag-sommerkerze","product_tag-sommerkerze-bienen","first","instock","shipping-taxable","purchasable","product-type-simple","add-to-wishlist-after_add_to_cart","has-product-safety-information"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lavendel-Honig Duftkerze - Emmys Kerzen<\/title>\n<meta name=\"description\" content=\"Handgefertigte Lavendel-Honig Duftkerze aus 100 % Sojawachs. Mit Biene und Waben verziert \u2013 liebevoll gefertigt in \u00d6sterreich.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emmyskerzen.com\/en\/shop\/lavendel-honig-duftkerze\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavendel-Honig Duftkerze - Emmys Kerzen\" \/>\n<meta property=\"og:description\" content=\"Handgefertigte Lavendel-Honig Duftkerze aus 100 % Sojawachs. Mit Biene und Waben verziert \u2013 liebevoll gefertigt in \u00d6sterreich.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emmyskerzen.com\/en\/shop\/lavendel-honig-duftkerze\/\" \/>\n<meta property=\"og:site_name\" content=\"Emmys Kerzen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EmmysKerzen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T19:18:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emmyskerzen.com\/wp-content\/uploads\/2026\/07\/CC38CD72-FCB8-4E87-A221-8FC2AEDF1114.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1086\" \/>\n\t<meta property=\"og:image:height\" content=\"1448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/shop\\\/lavendel-honig-duftkerze\\\/\",\"url\":\"https:\\\/\\\/emmyskerzen.com\\\/shop\\\/lavendel-honig-duftkerze\\\/\",\"name\":\"Lavendel-Honig Duftkerze - Emmys Kerzen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/shop\\\/lavendel-honig-duftkerze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/shop\\\/lavendel-honig-duftkerze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emmyskerzen.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/CC38CD72-FCB8-4E87-A221-8FC2AEDF1114.png\",\"datePublished\":\"2026-07-03T13:43:37+00:00\",\"dateModified\":\"2026-09-01T19:18:03+00:00\",\"description\":\"Handgefertigte Lavendel-Honig Duftkerze aus 100 % Sojawachs. Mit Biene und Waben verziert \u2013 liebevoll gefertigt in \u00d6sterreich.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/shop\\\/lavendel-honig-duftkerze\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/emmyskerzen.com\\\/shop\\\/lavendel-honig-duftkerze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/shop\\\/lavendel-honig-duftkerze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emmyskerzen.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/CC38CD72-FCB8-4E87-A221-8FC2AEDF1114.png\",\"contentUrl\":\"https:\\\/\\\/emmyskerzen.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/CC38CD72-FCB8-4E87-A221-8FC2AEDF1114.png\",\"width\":1086,\"height\":1448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/shop\\\/lavendel-honig-duftkerze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/emmyskerzen.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kerzen Shop\",\"item\":\"https:\\\/\\\/emmyskerzen.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lavendel-Honig Duftkerze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/#website\",\"url\":\"https:\\\/\\\/emmyskerzen.com\\\/\",\"name\":\"Emmys Kerzen\",\"description\":\"Hochwertige handgemachte Kerzen aus \u00d6sterreich \u2013 perfekt als Geschenk oder f\u00fcr dein Zuhause. Jetzt entdecken!\",\"publisher\":{\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/emmyskerzen.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/#organization\",\"name\":\"Emmys Kerzen\",\"url\":\"https:\\\/\\\/emmyskerzen.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/emmyskerzen.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_0392.jpeg\",\"contentUrl\":\"https:\\\/\\\/emmyskerzen.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_0392.jpeg\",\"width\":964,\"height\":975,\"caption\":\"Emmys Kerzen\"},\"image\":{\"@id\":\"https:\\\/\\\/emmyskerzen.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EmmysKerzen\\\/\",\"https:\\\/\\\/www.instagram.com\\\/emmys_kerzen\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/emmys.kerzen\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lavendel-Honig Duftkerze - Emmys Kerzen","description":"Handgefertigte Lavendel-Honig Duftkerze aus 100 % Sojawachs. Mit Biene und Waben verziert \u2013 liebevoll gefertigt in \u00d6sterreich.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emmyskerzen.com\/en\/shop\/lavendel-honig-duftkerze\/","og_locale":"en_GB","og_type":"article","og_title":"Lavendel-Honig Duftkerze - Emmys Kerzen","og_description":"Handgefertigte Lavendel-Honig Duftkerze aus 100 % Sojawachs. Mit Biene und Waben verziert \u2013 liebevoll gefertigt in \u00d6sterreich.","og_url":"https:\/\/emmyskerzen.com\/en\/shop\/lavendel-honig-duftkerze\/","og_site_name":"Emmys Kerzen","article_publisher":"https:\/\/www.facebook.com\/EmmysKerzen\/","article_modified_time":"2026-09-01T19:18:03+00:00","og_image":[{"width":1086,"height":1448,"url":"https:\/\/emmyskerzen.com\/wp-content\/uploads\/2026\/07\/CC38CD72-FCB8-4E87-A221-8FC2AEDF1114.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/emmyskerzen.com\/shop\/lavendel-honig-duftkerze\/","url":"https:\/\/emmyskerzen.com\/shop\/lavendel-honig-duftkerze\/","name":"Lavendel-Honig Duftkerze - Emmys Kerzen","isPartOf":{"@id":"https:\/\/emmyskerzen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emmyskerzen.com\/shop\/lavendel-honig-duftkerze\/#primaryimage"},"image":{"@id":"https:\/\/emmyskerzen.com\/shop\/lavendel-honig-duftkerze\/#primaryimage"},"thumbnailUrl":"https:\/\/emmyskerzen.com\/wp-content\/uploads\/2026\/07\/CC38CD72-FCB8-4E87-A221-8FC2AEDF1114.png","datePublished":"2026-07-03T13:43:37+00:00","dateModified":"2026-09-01T19:18:03+00:00","description":"Handgefertigte Lavendel-Honig Duftkerze aus 100 % Sojawachs. Mit Biene und Waben verziert \u2013 liebevoll gefertigt in \u00d6sterreich.","breadcrumb":{"@id":"https:\/\/emmyskerzen.com\/shop\/lavendel-honig-duftkerze\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emmyskerzen.com\/shop\/lavendel-honig-duftkerze\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/emmyskerzen.com\/shop\/lavendel-honig-duftkerze\/#primaryimage","url":"https:\/\/emmyskerzen.com\/wp-content\/uploads\/2026\/07\/CC38CD72-FCB8-4E87-A221-8FC2AEDF1114.png","contentUrl":"https:\/\/emmyskerzen.com\/wp-content\/uploads\/2026\/07\/CC38CD72-FCB8-4E87-A221-8FC2AEDF1114.png","width":1086,"height":1448},{"@type":"BreadcrumbList","@id":"https:\/\/emmyskerzen.com\/shop\/lavendel-honig-duftkerze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/emmyskerzen.com\/"},{"@type":"ListItem","position":2,"name":"Kerzen Shop","item":"https:\/\/emmyskerzen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Lavendel-Honig Duftkerze"}]},{"@type":"WebSite","@id":"https:\/\/emmyskerzen.com\/#website","url":"https:\/\/emmyskerzen.com\/","name":"Emmys Kerzen","description":"Hochwertige handgemachte Kerzen aus \u00d6sterreich \u2013 perfekt als Geschenk oder f\u00fcr dein Zuhause. Jetzt entdecken!","publisher":{"@id":"https:\/\/emmyskerzen.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emmyskerzen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/emmyskerzen.com\/#organization","name":"Emmys Kerzen","url":"https:\/\/emmyskerzen.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/emmyskerzen.com\/#\/schema\/logo\/image\/","url":"https:\/\/emmyskerzen.com\/wp-content\/uploads\/2026\/03\/IMG_0392.jpeg","contentUrl":"https:\/\/emmyskerzen.com\/wp-content\/uploads\/2026\/03\/IMG_0392.jpeg","width":964,"height":975,"caption":"Emmys Kerzen"},"image":{"@id":"https:\/\/emmyskerzen.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EmmysKerzen\/","https:\/\/www.instagram.com\/emmys_kerzen\/","https:\/\/www.tiktok.com\/emmys.kerzen\/"]}]}},"_links":{"self":[{"href":"https:\/\/emmyskerzen.com\/en\/wp-json\/wp\/v2\/product\/3279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emmyskerzen.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/emmyskerzen.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/emmyskerzen.com\/en\/wp-json\/wp\/v2\/comments?post=3279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emmyskerzen.com\/en\/wp-json\/wp\/v2\/media\/3280"}],"wp:attachment":[{"href":"https:\/\/emmyskerzen.com\/en\/wp-json\/wp\/v2\/media?parent=3279"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/emmyskerzen.com\/en\/wp-json\/wp\/v2\/product_brand?post=3279"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/emmyskerzen.com\/en\/wp-json\/wp\/v2\/product_cat?post=3279"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/emmyskerzen.com\/en\/wp-json\/wp\/v2\/product_tag?post=3279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}